{"id":155905,"date":"2023-10-20T00:00:30","date_gmt":"2023-10-20T00:00:30","guid":{"rendered":"https:\/\/www.portalminero.com\/wp\/ministerio-de-mineria-lanza-proceso-de-participacion-de-plan-sectorial-cambio-climatico-para-el-sector\/"},"modified":"2023-10-20T16:44:53","modified_gmt":"2023-10-20T16:44:53","slug":"ministerio-de-mineria-lanza-proceso-de-participacion-de-plan-sectorial-cambio-climatico-para-el-sector","status":"publish","type":"post","link":"http:\/\/200.6.115.193\/wp\/ministerio-de-mineria-lanza-proceso-de-participacion-de-plan-sectorial-cambio-climatico-para-el-sector\/","title":{"rendered":"Ministerio de Miner\u00eda lanza proceso de participaci\u00f3n de Plan Sectorial Cambio Clim\u00e1tico para el sector"},"content":{"rendered":"<h6><em>Chile<\/em><\/h6>\n<p><b>Iniciativa responde a la meta pa\u00eds de alcanzar la carbono neutralidad y resiliencia al cambio clim\u00e1tico al a\u00f1o 2050.<\/b><\/p>\n<p><img decoding=\"async\" class=\"imagen-noticia\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"http:\/\/pm.portalminero.com\/images\/noticias\/653295db637d8.jpg\" alt=\"Ministerio de Miner\u00eda lanza proceso de participaci\u00f3n de Plan Sectorial Cambio Clim\u00e1tico para el sector\" \/><noscript><img decoding=\"async\" class=\"imagen-noticia\" src=\"http:\/\/pm.portalminero.com\/images\/noticias\/653295db637d8.jpg\" alt=\"Ministerio de Miner\u00eda lanza proceso de participaci\u00f3n de Plan Sectorial Cambio Clim\u00e1tico para el sector\" \/><\/noscript><\/p>\n<div class=\"texto_prensa\" align=\"justify\">\n<p><strong>viernes 20 de octubre del 2023.-<\/strong>\u00a0Junto a actores de la industria y la presencia de la ministra de Miner\u00eda, Aurora Williams, la subsecretaria de la cartera, Suina Chahu\u00e1n y el subsecretario de Medioambiente, Maximiliano Proa\u00f1o, se dio inicio al proceso participativo para la elaboraci\u00f3n del anteproyecto del Plan Sectorial de Cambio Clim\u00e1tico en Miner\u00eda.<\/p>\n<p>La iniciativa responde a la meta pa\u00eds de alcanzar la carbono neutralidad y resiliencia al cambio clim\u00e1tico al a\u00f1o 2050, en l\u00ednea con la serie de instrumentos de gesti\u00f3n para la acci\u00f3n clim\u00e1tica que propone la Ley Marco de Cambio Clim\u00e1tico promulgada el a\u00f1o pasado y que consagra responsabilidades y obligaciones a 13 ministerios y a todas las regiones y comunas del pa\u00eds.<\/p>\n<p>De esta manera, el ministerio de Miner\u00eda inici\u00f3 el proceso de elaboraci\u00f3n de un plan de mitigaci\u00f3n y adaptaci\u00f3n sobre esta materia en el sector minero. \u201cEn nuestra industria \u2013 afirm\u00f3 la titular de la cartera, Aurora Williams \u2013 la manera en que tenemos que enfrentar la emergencia clim\u00e1tica es implementando cambios sustanciales. En nuestros procesos, en nuestra vinculaci\u00f3n con los territorios, de manera que exista un equilibrio en temas ambientales, productivos y sociales. El desaf\u00edo entonces no es menor. Cuando se definen pol\u00edticas de largo plazo es necesario establecer hitos intermedios que vayan verificando los avances en pro de los objetivos trazados y para ello estamos ac\u00e1\u201d.<\/p>\n<p>Asimismo, la autoridad agreg\u00f3 que siendo la miner\u00eda un sector relevante para la econom\u00eda chilena, \u201ces crucial tambi\u00e9n para enfrentar el gran desaf\u00edo que implica el cambio clim\u00e1tico en el mundo, se necesita de m\u00e1s y mejor miner\u00eda para proveer los minerales que requiere la transici\u00f3n energ\u00e9tica y Chile es un actor clave. Hoy partimos un tema importante en este plan que es el proceso de participaci\u00f3n. Espero que todas y todos puedan sumarse y ser escuchados, para que, efectivamente, desde nuestro sector colaboremos de manera decisiva\u201d, manifest\u00f3 la ministra de Miner\u00eda, Aurora Williams.<\/p>\n<p>La actividad incluy\u00f3 un panel de conversaci\u00f3n con actores de la industria, que fue moderado por la subsecretaria de Miner\u00eda, Suina Chahu\u00e1n.<\/p>\n<p>\u201cEs esencial destacar la necesidad de la colaboraci\u00f3n p\u00fablico-privada y la importancia de que en las distintas etapas de este proceso trabajemos en conjunto. El cambio clim\u00e1tico nos afecta a todos por igual y, para enfrentarlo, es fundamental que los diferentes actores de la cadena minera colaboren estrechamente. Desde el ministerio estamos comprometidos en generar las condiciones habilitantes que la industria requiere. La miner\u00eda chilena ya ha dado pasos significativos en la mitigaci\u00f3n del cambio clim\u00e1tico y se ha propuesto metas ambiciosas para el futuro. Estamos aqu\u00ed para apoyar y facilitar este proceso, asegurando que nuestra miner\u00eda avance hacia la sostenibilidad\u201d, sostuvo la subsecretaria Chahu\u00e1n en el encuentro.<\/p>\n<p>Por su parte, el subsecretario de Medioambiente, Maximiliano Proa\u00f1o, explic\u00f3 que, \u201cestos planes sectoriales son una hoja de ruta para mitigar y adaptarnos de mejor manera a los eventos extremos clim\u00e1ticos que hemos visto durante este \u00faltimo tiempo. Sin duda nos urge tambi\u00e9n apurar el tranco en cuanto a la implementaci\u00f3n, para dar seguridad y certeza al sector y a la poblaci\u00f3n. Sabemos que los mercados son cada vez m\u00e1s m\u00e1s exigentes en esta materia y entendemos que el sector est\u00e1 embarcado en este proceso. Este plan va a permitir tener mayor claridad de aquello\u201d.<\/p>\n<p>Desde sus inicios, el plan sectorial de Cambio Clim\u00e1tico en Miner\u00eda cont\u00f3 con el apoyo del Banco Interamericano del Desarrollo, representado en Chile por Mar\u00eda Florencia Attademo-Hirt, qui\u00e9n indic\u00f3 que este \u201ceste tipo de procesos est\u00e1 alineado con un objetivo institucional que tiene como norte, la sostenibilidad y el pensar en matrices productivas m\u00e1s verdes para Chile y su gente, pensando en la transformaci\u00f3n hacia la descarbonizaci\u00f3n como una oportunidad. Queremos escuchar a todos y a todas. El gobierno, la sociedad civil, la industria y las comunidades afectadas cuentan con nosotros para este proceso. No son \u00fanicos en la regi\u00f3n en cuanto a riqueza de minerales, pero s\u00ed son l\u00edderes. Entonces hay vecinos y vecinas que est\u00e1n observando lo que ocurre en Chile, por lo que podemos aprender y exportar mejores pr\u00e1cticas para la regi\u00f3n\u201d, sostuvo.<\/p>\n<p>Las y los interesados en sumarse a esta iniciativa, deben ingresar al sitio web <a href=\"https:\/\/participa.minmineria.gob.cl\/es-CL\/\">participa.minmineria.gob.cl\/es-CL\/<\/a> e ingresar sus datos en formulario de inscripci\u00f3n.<\/p>\n<p>El Plan Sectorial de Cambio Clim\u00e1tico en Miner\u00eda debe estar promulgado como m\u00e1ximo dos a\u00f1os de la publicaci\u00f3n de la ley, es decir, en junio de 2024.<\/p>\n<\/div>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p><span class='published'>Chile | 2023-10-20<\/span><\/p>\n<p>Iniciativa responde a la meta pa\u00eds de alcanzar la carbono neutralidad y resiliencia al cambio clim\u00e1tico al a\u00f1o 2050.<\/p>\n","protected":false},"author":26,"featured_media":155906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-155905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/155905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/comments?post=155905"}],"version-history":[{"count":2,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/155905\/revisions"}],"predecessor-version":[{"id":155911,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/155905\/revisions\/155911"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/media\/155906"}],"wp:attachment":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/media?parent=155905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/categories?post=155905"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/tags?post=155905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}