{"id":156129,"date":"2023-10-24T00:00:30","date_gmt":"2023-10-24T00:00:30","guid":{"rendered":"https:\/\/www.portalminero.com\/wp\/acuerdo-por-valparaiso-impulsara-las-inversiones-y-el-desarrollo-portuario-de-la-ciudad\/"},"modified":"2023-10-24T15:57:04","modified_gmt":"2023-10-24T15:57:04","slug":"acuerdo-por-valparaiso-impulsara-las-inversiones-y-el-desarrollo-portuario-de-la-ciudad","status":"publish","type":"post","link":"http:\/\/200.6.115.193\/wp\/acuerdo-por-valparaiso-impulsara-las-inversiones-y-el-desarrollo-portuario-de-la-ciudad\/","title":{"rendered":"\u201cAcuerdo por Valpara\u00edso\u201d impulsar\u00e1 las inversiones y el desarrollo portuario de la ciudad"},"content":{"rendered":"<h6><em>Chile<\/em><\/h6>\n<p><b>El texto marca un hito para un proyecto de inversi\u00f3n en el pa\u00eds, ya que se logr\u00f3 aunar los intereses y preocupaciones de la mayor\u00eda en torno al desarrollo de la ampliaci\u00f3n y la expansi\u00f3n futura del puerto.<\/b><\/p>\n<p><img decoding=\"async\" class=\"imagen-noticia\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"http:\/\/pm.portalminero.com\/images\/noticias\/6537e4bee5264.jpg\" alt=\"\u201cAcuerdo por Valpara\u00edso\u201d impulsar\u00e1 las inversiones y el desarrollo portuario de la ciudad\" \/><noscript><img decoding=\"async\" class=\"imagen-noticia\" src=\"http:\/\/pm.portalminero.com\/images\/noticias\/6537e4bee5264.jpg\" alt=\"\u201cAcuerdo por Valpara\u00edso\u201d impulsar\u00e1 las inversiones y el desarrollo portuario de la ciudad\" \/><\/noscript><\/p>\n<div class=\"texto_prensa\" align=\"justify\">\n<p><strong>martes 24 de octubre del 2023.-<\/strong> En un hecho in\u00e9dito para un proyecto de inversi\u00f3n en el pa\u00eds, se firm\u00f3 el \u201cAcuerdo por Valpara\u00edso\u201d con consensos y compromisos para impulsar la expansi\u00f3n de la actividad portuaria en el marco de una nueva relaci\u00f3n entre el puerto, la ciudad y la regi\u00f3n. El documento fue suscrito por la Empresa Portuaria Valpara\u00edso, la Ilustre Municipalidad de Valpara\u00edso y el Gobierno Regional, y entregado al Presidente de la Rep\u00fablica Gabriel Boric en un acto celebrado en el Terminal de Pasajeros de Valpara\u00edso.<\/p>\n<p>A la actividad asistieron el ministro de Transportes, Juan Carlos Mu\u00f1oz, parlamentarios, l\u00edderes gremiales y empresariales, sindicatos de trabajadores portuarios, autoridades de la Armada, acad\u00e9micos y un importante n\u00famero de vecinos, vecinas y dirigentes de la comunidad porte\u00f1a.<\/p>\n<p>En su discurso, el Presidente Gabriel Boric afirm\u00f3 que \u201ctodos queremos a Valpara\u00edso y queremos lo mejor para la ciudad. Este acuerdo da cuenta de una lucidez y capacidad tremenda, porque ac\u00e1 no se est\u00e1 imponiendo un proyecto, sino que se construy\u00f3 desde abajo, con la gente y para la gente\u201d. Agreg\u00f3 que Chile requiere actualizar su infraestructura portuaria, \u201cnecesitamos que Valpara\u00edso avance en su modernizaci\u00f3n, necesitamos m\u00e1s y mejores puertos, y esta ciudad puerto, para ello, es esencial\u201d.<\/p>\n<p>El presidente Luis Eduardo Escobar afirm\u00f3 que \u201ceste acuerdo es in\u00e9dito en Chile porque abre un nuevo camino en las relaciones puerto, ciudad y regi\u00f3n, en el desarrollo de grandes proyectos de infraestructura, en la actividad portuaria y, sobre todo, en la convivencia entre las distintas vocaciones y actividades que se desarrollan en Valpara\u00edso\u201d.<\/p>\n<p>Agreg\u00f3 que el proyecto relanzar\u00e1 la econom\u00eda de Valpara\u00edso. \u201cEstamos hablando de una inversi\u00f3n de US$ 600 millones, que ser\u00eda la inversi\u00f3n no minera en la regi\u00f3n m\u00e1s grande de los \u00faltimos a\u00f1os. Adem\u00e1s, la construcci\u00f3n del muelle cruceros significa que vamos a facilitar llegada de turistas a Valpara\u00edso, con todo lo que eso significa para la actividad econ\u00f3mica; y tambi\u00e9n vamos a ampliar el n\u00famero de gente que trabaja en el puerto\u201d, destac\u00f3.<\/p>\n<p>A su vez, el gobernador Rodrigo Mundaca subray\u00f3 que \u201ceste acuerdo por Valpara\u00edso incorpora una mirada del desarrollo estrat\u00e9gico portuario, donde este no establece un marco de competencia con el Puerto de San Antonio, sino que, muy por el contrario, incorpora una mirada de reciprocidad, solidaridad y apoyo conjunto\u201d.<\/p>\n<p>El alcalde Jorge Sharp afirm\u00f3 que \u201cesperamos que este sea el primer d\u00eda del resurgimiento de Valpara\u00edso. Lo que hacemos, luego de dos d\u00e9cadas, es poner de acuerdo a toda la ciudad en torno a la ampliaci\u00f3n de puerto y esto va a significar una nueva relaci\u00f3n m\u00e1s solidaria entre el puerto y la ciudad. Buscamos que el puerto aporte econ\u00f3micamente y de esa manera apoyar otras vocaciones econ\u00f3micas de la ciudad como turismo, el patrimonio, la ciudad universitaria\u201d.<\/p>\n<p>Elena Carvajal, presidenta de la Junta de Vecinos Rapa Nui de Rodelillo, afirm\u00f3 que \u201ctodo lo que se invierta en Valpara\u00edso y en apoyo a los porte\u00f1os es bienvenido. Ahora hay un acuerdo transversal y eso es muy importante porque a Valpara\u00edso le hace falta aporte econ\u00f3mico para la inversi\u00f3n, y que el puerto tenga la vida que ten\u00eda antes\u201d.<\/p>\n<p>El texto entregado al Presidente Boric, el que tambi\u00e9n fue firmado por representantes de distintos sectores de la ciudad y la regi\u00f3n, p\u00fablicos y privados, marca un hito relevante para un proyecto de inversi\u00f3n en el pa\u00eds, ya que se logr\u00f3 aunar los intereses y preocupaciones de la mayor\u00eda en torno al desarrollo de la ampliaci\u00f3n, la expansi\u00f3n futura del puerto y una mirada m\u00e1s amplia sobre el borde costero de la ciudad como oportunidad de crecimiento.<\/p>\n<p>Entre los aspectos centrales del documento, los firmantes comprometieron el desarrollo de nuevos terminales portuarios en las aguas protegidas por el molo de abrigo, la creaci\u00f3n de un muelle de cruceros de uso mixto que pueda transferir cargas cuando no exista llegada de naves tur\u00edsticas, y el desarrollo de un Plan Estrat\u00e9gico para el Borde Costero con participaci\u00f3n ciudadana, que ayude a priorizar obras e inversiones que distintos actores p\u00fablicos y privados realicen para mejorar la relaci\u00f3n de los porte\u00f1os, porte\u00f1as y visitantes con el mar.<\/p>\n<p>En el acuerdo se plasman los consensos alcanzados en el proceso de di\u00e1logo ciudadano Valpara\u00edso Dialoga, que fue impulsado por la empresa estatal desde 2021 y en el cual participaron m\u00e1s de 500 personas representantes de todas las vocaciones e intereses de la ciudad, y se recogen tambi\u00e9n aspectos centrales del Pladeco comunal y de la estrategia de Desarrollo Regional.<\/p>\n<p>Adem\u00e1s, se contempla la colaboraci\u00f3n de la empresa portuaria con la municipalidad y el gobierno regional, entre otros actores, para aportar al debate en torno a los mayores aportes econ\u00f3micos que los puertos estatales podr\u00edan dejar en las comunas que los acogen, as\u00ed como f\u00f3rmulas para que las autoridades locales integren sus directorios, tal como se explora en la pol\u00edtica de desarrollo log\u00edstico que impulsa el Ministerio de Transportes.<\/p>\n<\/div>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p><span class='published'>Chile | 2023-10-24<\/span><\/p>\n<p>El texto marca un hito para un proyecto de inversi\u00f3n en el pa\u00eds, ya que se logr\u00f3 aunar los intereses y preocupaciones de la mayor\u00eda en torno al desarrollo de la ampliaci\u00f3n y la expansi\u00f3n futura del puerto.<\/p>\n","protected":false},"author":26,"featured_media":156130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-156129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/156129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/comments?post=156129"}],"version-history":[{"count":2,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/156129\/revisions"}],"predecessor-version":[{"id":156134,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/156129\/revisions\/156134"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/media\/156130"}],"wp:attachment":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/media?parent=156129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/categories?post=156129"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/tags?post=156129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}