{"id":156202,"date":"2023-10-25T00:00:30","date_gmt":"2023-10-25T00:00:30","guid":{"rendered":"https:\/\/www.portalminero.com\/wp\/promueven-que-enami-sea-designada-como-compradora-unica-de-chatarra-de-cobre\/"},"modified":"2023-10-25T02:39:04","modified_gmt":"2023-10-25T02:39:04","slug":"promueven-que-enami-sea-designada-como-compradora-unica-de-chatarra-de-cobre","status":"publish","type":"post","link":"http:\/\/200.6.115.193\/wp\/promueven-que-enami-sea-designada-como-compradora-unica-de-chatarra-de-cobre\/","title":{"rendered":"Promueven que Enami sea designada como compradora \u00fanica de chatarra de cobre"},"content":{"rendered":"<h6><em>Chile<\/em><\/h6>\n<p><b>La idea de la resoluci\u00f3n es prevenir y evitar el comercio ilegal de cobre y otros minerales, en todas sus formas, en Chile.<\/b><\/p>\n<p><img decoding=\"async\" class=\"imagen-noticia\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"http:\/\/pm.portalminero.com\/images\/noticias\/65387d8dabf6a.jpg\" alt=\"Promueven que Enami sea designada como compradora \u00fanica de chatarra de cobre\" \/><noscript><img decoding=\"async\" class=\"imagen-noticia\" src=\"http:\/\/pm.portalminero.com\/images\/noticias\/65387d8dabf6a.jpg\" alt=\"Promueven que Enami sea designada como compradora \u00fanica de chatarra de cobre\" \/><\/noscript><\/p>\n<div class=\"texto_prensa\" align=\"justify\">\n<p><strong>mi\u00e9rcoles 25 de octubre del 2023.-<\/strong> La C\u00e1mara de Diputadas y Diputados solicit\u00f3 al Gobierno implementar modificaciones t\u00e9cnicas y legislativas para que designen a la Empresa Nacional de Miner\u00eda (Enami) como compradora \u00fanica de chatarra de cobre.<\/p>\n<p>La idea de la <a href=\"https:\/\/www.camara.cl\/legislacion\/resoluciones\/resolucion_documentos.aspx?prmId=\">resoluci\u00f3n 511<\/a> es prevenir y evitar el comercio ilegal de este producto\u00a0 en el pa\u00eds. Seg\u00fan se resalta, actualmente, existen en Chile bandas de crimen organizado abocadas al robo de cobre o de otros metales en sus diversas formas.<\/p>\n<p>Generalmente, ocupan la violencia mediante el robo a mineras de cobre o empresas que lo transportan. A ello se suma la vandalizaci\u00f3n de infraestructura el\u00e9ctrica, de telecomunicaciones o de energ\u00edas renovables, como en el caso de los paneles solares.<\/p>\n<p><strong>Rol de Enami<\/strong><\/p>\n<p>A juicio de las y los diputados, se trata de delitos que en los \u00faltimos tres a\u00f1os solo han ido en aumento. Esto perjudica gravemente a las empresas de servicio, como tambi\u00e9n a los miles de usuarios de estas.<\/p>\n<p>El objetivo de la resoluci\u00f3n es que el Gobierno implemente las modificaciones t\u00e9cnicas y legislativas para que la Empresa Nacional de Miner\u00eda sea designada como compradora \u00fanica de chatarra de cobre. La idea es prevenir y evitar el comercio ilegal de este producto en el pa\u00eds.<\/p>\n<p>La resoluci\u00f3n la presentaron las independientes Natalia Romero y Marlene P\u00e9rez (IND). Tambi\u00e9n la suscriben, desde la UDI, Renzo Trisotti, Marta Bravo, \u00c1lvaro Carter, Eduardo Cornejo y Daniel Lilayu.<\/p>\n<\/div>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p><span class='published'>Chile | 2023-10-25<\/span><\/p>\n<p>La idea de la resoluci\u00f3n es prevenir y evitar el comercio ilegal de cobre y otros minerales, en todas sus formas, en Chile.<\/p>\n","protected":false},"author":26,"featured_media":156203,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-156202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/156202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/comments?post=156202"}],"version-history":[{"count":2,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/156202\/revisions"}],"predecessor-version":[{"id":156205,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/156202\/revisions\/156205"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/media\/156203"}],"wp:attachment":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/media?parent=156202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/categories?post=156202"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/tags?post=156202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}