{"id":156698,"date":"2023-11-03T00:00:00","date_gmt":"2023-11-03T00:00:00","guid":{"rendered":"https:\/\/www.portalminero.com\/wp\/con-gran-convocatoria-de-estudiantes-se-realizo-primera-feria-profesional-de-quimica-de-la-puc\/"},"modified":"2023-11-08T01:22:17","modified_gmt":"2023-11-08T01:22:17","slug":"con-gran-convocatoria-de-estudiantes-se-realizo-primera-feria-profesional-de-quimica-de-la-puc","status":"publish","type":"post","link":"http:\/\/200.6.115.193\/wp\/con-gran-convocatoria-de-estudiantes-se-realizo-primera-feria-profesional-de-quimica-de-la-puc\/","title":{"rendered":"Con gran convocatoria de estudiantes se realiz\u00f3 primera feria profesional de Qu\u00edmica de la PUC"},"content":{"rendered":"<h6><b>Chile<\/b><\/h6>\n<p><strong>La actividad fue coorganizada por la Asociaci\u00f3n Gremial de Industriales Qu\u00edmicos de Chile, Asiquim. En total, 18 empresas del rubro estuvieron presentes con potenciales vacantes para pr\u00e1cticas profesionales y primeros trabajos para los y las estudiantes de la carrera.<\/strong><\/p>\n<p><img decoding=\"async\" class=\"imagen-noticia\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/www.portalminero.com\/wp\/wp-content\/uploads\/subidos\/notasprensa\/15565_65444d37ec44c.jpg\" alt=\"Con gran convocatoria de estudiantes se realiz\u00f3 primera feria profesional de Qu\u00edmica de la PUC\" \/><noscript><img decoding=\"async\" class=\"imagen-noticia\" src=\"https:\/\/www.portalminero.com\/wp\/wp-content\/uploads\/subidos\/notasprensa\/15565_65444d37ec44c.jpg\" alt=\"Con gran convocatoria de estudiantes se realiz\u00f3 primera feria profesional de Qu\u00edmica de la PUC\" \/><\/noscript><\/p>\n<div class=\"texto_prensa\" align=\"justify\">\n<p><strong>viernes 03 de noviembre del 2023.-<\/strong> Un \u00e9xito result\u00f3 la \u201cPrimera Feria Profesional para Qu\u00edmica: Pr\u00e1cticas y Primeros Trabajos\u201d, que se llev\u00f3 a cabo en la Facultad de Qu\u00edmica y Farmacia de la Universidad Cat\u00f3lica, con el objetivo de fortalecer la vinculaci\u00f3n entre los estudiantes de la carrera de Qu\u00edmica con la industria, difundir que hacen las empresas socias de Asiquim y c\u00f3mo los estudiantes de qu\u00edmica pueden visualizar su campo laboral dentro de las distintas opciones de desarrollo que tienen los futuros profesionales de esta carrera.<\/p>\n<p>Un gran n\u00famero de estudiantes asisti\u00f3 a la actividad, organizada por la Escuela de Qu\u00edmica, con el apoyo de Asiquim, el Colegio Chileno de Qu\u00edmicos y Ciencia2030. Archroma, Austral Chemicals, BASF, Cloramon, Codelpa, Dexima, HB Fuller, Linde, Mathiesen, Newchem, Noracid, Oxiquim, Panimex, Proquiel, Qu\u00edmica Rhenium, Salimax y SQM fueron las compa\u00f1\u00edas de la industria que participaron en el evento con potenciales vacantes para pr\u00e1cticas profesionales y primeros trabajos para los y las estudiantes<strong>. <\/strong>Tambi\u00e9n, estuvieron presentes el Centro de Desarrollo Profesional UC, con un stand que entreg\u00f3 informaci\u00f3n sobre orientaci\u00f3n profesional y herramientas de empleabilidad, el Colegio Profesional de Qu\u00edmicos, quienes dieron toda la informaci\u00f3n del rol a nivel profesional, la EQUC (Estudiantes de Qu\u00edmica UC), organizaci\u00f3n que lidera la difusi\u00f3n con los estudiantes; y los tesistas de Qu\u00edmica UC, con presentaci\u00f3n de paneles con sus tesis.<\/p>\n<p>La subdirectora de la Escuela de Qu\u00edmica, Flavia Zacconi, se\u00f1al\u00f3 que esta feria es necesaria tanto para los y las estudiantes como para la escuela, \u201cpara relacionarnos m\u00e1s estrechamente con las industrias, no \u00fanicamente por el hecho de que el estudiantado logre trabajar profesionalmente, sino que tambi\u00e9n para generar una interacci\u00f3n previa. Por ejemplo, pr\u00e1cticas profesionales, seminarios, tesis, e ir incrementando nuestra relaci\u00f3n a trav\u00e9s del tiempo hasta lograr (tal vez) proyectos de inter\u00e9s p\u00fablico, social o nacional\u201d.<\/p>\n<p>Por su parte, el gerente general de Asiquim, Sergio Barrientos, manifest\u00f3 que \u201cestamos muy conformes y contentos con los resultados de esta feria, y con los lazos que se han ido generando entre la PUC y nuestro gremio, los cuales queremos seguir fortaleciendo. Asiquim tiene 130 empresas a nivel nacional, las cuales pueden capturar a profesionales de Qu\u00edmica de la Universidad Cat\u00f3lica, para que aporten al desarrollo de nuestra industria\u201d.<\/p>\n<p>El profesional agreg\u00f3 que uno de los objetivos del gremio es contribuir a la formaci\u00f3n de profesionales para la industria qu\u00edmica, a trav\u00e9s de la vinculaci\u00f3n industria-universidad. \u201cEs por esto que, entre otras actividades de vinculaci\u00f3n, promovimos la organizaci\u00f3n de esta primera feria profesional de Qu\u00edmica de la PUC. Asiquim tambi\u00e9n se vincula con el mundo acad\u00e9mico impartiendo un ramo en seis universidades de Chile, a los futuros profesionales del \u00e1rea, en temas como el sistema de gesti\u00f3n Responsible Care\u00ae, iniciativa de la industria qu\u00edmica mundial para promover el desarrollo sostenible\u201d, resalt\u00f3 Barrientos.<\/p>\n<\/div>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p><span class='published'>Chile | 2023-11-03 <\/p>\n<p>La actividad fue coorganizada por la Asociaci\u00f3n Gremial de Industriales Qu\u00edmicos de Chile, Asiquim. En total, 18 empresas del rubro estuvieron presentes con potenciales vacantes para pr\u00e1cticas profesionales y primeros trabajos para los y las estudiantes de la carrera.<\/p>\n","protected":false},"author":26,"featured_media":156699,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-156698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/156698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/comments?post=156698"}],"version-history":[{"count":2,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/156698\/revisions"}],"predecessor-version":[{"id":156954,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/156698\/revisions\/156954"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/media\/156699"}],"wp:attachment":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/media?parent=156698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/categories?post=156698"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/tags?post=156698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}