{"id":88323,"date":"2019-12-06T00:06:30","date_gmt":"2019-12-06T00:06:30","guid":{"rendered":"http:\/\/www.portalminero.com\/wp\/amtc-organiza-escuela-de-verano-internacional-sobre-aplicaciones-de-inteligencia-artificial-en-robotica\/"},"modified":"2020-01-20T12:04:06","modified_gmt":"2020-01-20T12:04:06","slug":"amtc-organiza-escuela-de-verano-internacional-sobre-aplicaciones-de-inteligencia-artificial-en-robotica","status":"publish","type":"post","link":"http:\/\/200.6.115.193\/wp\/amtc-organiza-escuela-de-verano-internacional-sobre-aplicaciones-de-inteligencia-artificial-en-robotica\/","title":{"rendered":"AMTC organiza escuela de verano internacional sobre aplicaciones de inteligencia artificial en rob\u00f3tica"},"content":{"rendered":"<h6><em>Chile<\/em><\/h6>\n<p><b>El curso congregar\u00e1 a investigadores y estudiantes de posgrado, con investigadores de universidades de Chile y el extranjero.<\/b><\/p>\n<p><img decoding=\"async\" class=\"imagen-noticia\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"http:\/\/pm.portalminero.com\/images\/noticias\/5de8f1237407b.jpg\" alt=\"AMTC organiza escuela de verano internacional sobre aplicaciones de inteligencia artificial en rob\u00f3tica\" \/><noscript><img decoding=\"async\" class=\"imagen-noticia\" src=\"http:\/\/pm.portalminero.com\/images\/noticias\/5de8f1237407b.jpg\" alt=\"AMTC organiza escuela de verano internacional sobre aplicaciones de inteligencia artificial en rob\u00f3tica\" \/><\/noscript><\/p>\n<div class=\"texto_prensa\" align=\"justify\">\n<p><strong>viernes 06 de diciembre del 2019.-<\/strong>\u00a0Del 9 al 13 de diciembre se desarrollar\u00e1 en Santiago el \u00abIEEE RAS International Summer School on Deep Learning for Robot Vision\u00bb, evento que reunir\u00e1 a investigadores y estudiantes de mag\u00edster y doctorado de todo el mundo, especialistas en la aplicaci\u00f3n de t\u00e9cnicas de inteligencia artificial (deep learning) a sistemas rob\u00f3ticos.<\/p>\n<p>La escuela de verano es organizada por el Advanced Mining Technology Center, el Instituto de Ciencias de la Ingenier\u00eda de la Universidad de O\u2019Higgins y el IEEE RAS Technical Education Program. El IEEE RAS es la Sociedad de Automatizaci\u00f3n y Rob\u00f3tica del IEEE, la mayor asociaci\u00f3n de ingenieros del mundo.<\/p>\n<p>El objetivo de la escuela de verano es presentar los \u00faltimos avances y aplicaciones de aprendizaje profundo en rob\u00f3tica. Los temas espec\u00edficos a tratar ser\u00e1n aprendizaje reforzado profundo (deep reinforcement learning), y aplicaciones de aprendizaje profundo en tareas de percepci\u00f3n, manipulaci\u00f3n y navegaci\u00f3n aut\u00f3noma. Adem\u00e1s se analizar\u00e1n los fundamentos biol\u00f3gicos de las redes neuronales artificiales y el impacto \u00e9tico del uso de las nuevas herramientas de inteligencia artificial. Mayor informaci\u00f3n en el sitio http:\/\/robotvision2019.amtc.cl\/<\/p>\n<p>\u00abEsta escuela de verano en visi\u00f3n rob\u00f3tica es una de las 3 escuelas de verano que organiza el IEEE RAS en el mundo. Estamos muy orgullosos de ser los anfitriones de este importante evento cient\u00edfico internacional y de proveer un espacio para que se presenten en Chile, las investigaciones m\u00e1s recientes en el campo de la visi\u00f3n rob\u00f3tica, aspecto cr\u00edtico para las m\u00e1quinas aut\u00f3nomas del futuro\u00bb, detall\u00f3 el Dr. Javier Ruiz del Solar.<\/p>\n<p>Los expositores internacionales de esta escuela de verano son destacados investigadores en rob\u00f3tica: Juxi Leitner, del Centro Australiano de Excelencia para Visi\u00f3n Rob\u00f3tica; Jens Kober, de la Universidad Tecnol\u00f3gica de Delft; Niko S\u00fcnderhauf, de la Universidad Tecnol\u00f3gica de Queensland; Stefan Leutenegger, del Imperial College de Londres, y Wei Pan, tambi\u00e9n de la Universidad Tecnol\u00f3gica de Delft. Los expositores nacionales ser\u00e1n Javier Ruiz del Solar, director ejecutivo del AMTC y profesor titular del Departamento de Ingenier\u00eda El\u00e9ctrica de la Universidad de Chile; Wolfhart Totschnig, del Instituto de Filosof\u00eda de la Universidad Diego Portales; Pedro Maldonado, de la Facultad de Medicina de la Universidad de Chile; Rodrigo Verschae, de la Universidad de O\u2019Higgins; Alexandre Bergel, profesor asociado del Departamento de Ciencia de la Computaci\u00f3n de la Universidad de Chile; Mar\u00eda Jos\u00e9 Escobar, del Departamento de Electr\u00f3nica de la Universidad Federico Santa Mar\u00eda, y Nicol\u00e1s Cruz y Francisco Leiva, ambos estudiantes de postgrado del Departamento de Ingenier\u00eda El\u00e9ctrica de la Universidad de Chile.<\/p>\n<\/div>\n<hr \/>\n<p>Portal Minero<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class='published'>Chile | 2019-12-06<\/span><\/p>\n<p>El curso congregar\u00e1 a investigadores y estudiantes de posgrado, con investigadores de universidades de Chile y el extranjero.<\/p>\n","protected":false},"author":7,"featured_media":88324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-88323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/88323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/comments?post=88323"}],"version-history":[{"count":2,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/88323\/revisions"}],"predecessor-version":[{"id":88359,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/88323\/revisions\/88359"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/media\/88324"}],"wp:attachment":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/media?parent=88323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/categories?post=88323"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/tags?post=88323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}