{"id":88541,"date":"2019-12-12T00:12:30","date_gmt":"2019-12-12T00:12:30","guid":{"rendered":"http:\/\/www.portalminero.com\/wp\/cobre-sigue-en-racha-y-encadena-septima-alza-consecutiva\/"},"modified":"2020-01-17T16:12:48","modified_gmt":"2020-01-17T16:12:48","slug":"cobre-sigue-en-racha-y-encadena-septima-alza-consecutiva","status":"publish","type":"post","link":"http:\/\/200.6.115.193\/wp\/cobre-sigue-en-racha-y-encadena-septima-alza-consecutiva\/","title":{"rendered":"Cobre sigue en racha y encadena s\u00e9ptima alza consecutiva"},"content":{"rendered":"<h6><em>Internacional<\/em><\/h6>\n<p><b>Con esto, el metal rojo se ubica en US$2,76555 la libra en la Bolsa de Metales de Londres.<\/b><\/p>\n<p><img decoding=\"async\" class=\"imagen-noticia\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"http:\/\/pm.portalminero.com\/images\/noticias\/5df247ef0644f.jpg\" alt=\"Cobre sigue en racha y encadena s\u00e9ptima alza consecutiva\" \/><noscript><img decoding=\"async\" class=\"imagen-noticia\" src=\"http:\/\/pm.portalminero.com\/images\/noticias\/5df247ef0644f.jpg\" alt=\"Cobre sigue en racha y encadena s\u00e9ptima alza consecutiva\" \/><\/noscript><\/p>\n<div class=\"texto_prensa\" align=\"justify\">\n<p><strong>jueves 12 de diciembre del 2019.-<\/strong>\u00a0Una nueva alza present\u00f3 esta jornada el cobre en la Bolsa de Metales de Londres, tras escalar un 0,23%.<\/p>\n<p>La anterior, es la s\u00e9ptima sesi\u00f3n seguida de aumentos que presenta el metal rojo.<\/p>\n<p>Con el resultado de hoy, el commodity alcanz\u00f3 los US$2,76555 la libra, precio que se compara con los US$2,75920 las libras reportadas el mi\u00e9rcoles.<\/p>\n<p>Cabe destacar que la principal exportaci\u00f3n del pa\u00eds se ha visto beneficiada por los datos econ\u00f3micos de China, que han sido mejor de lo esperado, como el aumento de las importaciones.<\/p>\n<p>En este contexto, el promedio mensual del commodity lleg\u00f3 a los US$2,69298 la libra, mientras que la media anual alcanz\u00f3 los US$2,71803 la libra.<\/p>\n<\/div>\n<hr \/>\n<p>Portal Minero<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class='published'>Internacional | 2019-12-12<\/span><\/p>\n<p>Con esto, el metal rojo se ubica en US$2,76555 la libra en la Bolsa de Metales de Londres.<\/p>\n","protected":false},"author":7,"featured_media":88542,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-88541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/88541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/comments?post=88541"}],"version-history":[{"count":2,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/88541\/revisions"}],"predecessor-version":[{"id":90239,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/posts\/88541\/revisions\/90239"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/media\/88542"}],"wp:attachment":[{"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/media?parent=88541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/categories?post=88541"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/200.6.115.193\/wp\/wp-json\/wp\/v2\/tags?post=88541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}